{"id":4542,"date":"2021-11-04T06:00:00","date_gmt":"2021-11-04T06:00:00","guid":{"rendered":"https:\/\/www.ototech.es\/?p=4542"},"modified":"2021-10-22T10:52:05","modified_gmt":"2021-10-22T10:52:05","slug":"neurinoma-acustico-2","status":"publish","type":"post","link":"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/","title":{"rendered":"Neurinoma del ac\u00fastico: Todo acerca de esta cuesti\u00f3n"},"content":{"rendered":"\n<p>El mundo de la medicina es realmente apasionante. No solo porque permite curar infinidad de enfermedades, sino porque muchas de ellas son desconocidas para la mayor\u00eda. Es cierto que hay algunas muy conocidas por todos, pero de otras se sabe muy poco o nada. Por eso, cuando llega el diagn\u00f3stico, comienza una fase de investigaci\u00f3n para saber m\u00e1s sobre lo que te est\u00e1 ocurriendo, por supuesto, siempre contando con la orientaci\u00f3n de tu m\u00e9dico. Desde <strong>Ototech, expertos en <a href=\"http:\/\/ototech.es\/acufenos-barcelona\/\" target=\"_blank\" rel=\"noreferrer noopener\">ac\u00fafenos<\/a> e <a href=\"https:\/\/www.ototech.es\/hipoacusia\/\" target=\"_blank\" rel=\"noreferrer noopener\">hipoacusia <\/a>en Barcelona<\/strong>, queremos hablarte de un trastorno que no es demasiado frecuente: el <strong>neurinoma del ac\u00fastico<\/strong>.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice del art\u00edculo<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/#%C2%BFQue_es_el_neurinoma_del_acustico\" >\u00bfQu\u00e9 es el neurinoma del ac\u00fastico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/#%C2%BFQue_sintomas_presenta_el_neurinoma_del_acustico\" >\u00bfQu\u00e9 s\u00edntomas presenta el neurinoma del ac\u00fastico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/#_%C2%BFComo_se_realiza_el_diagnostico_del_neurinoma_del_acustico\" >&nbsp;\u00bfC\u00f3mo se realiza el diagn\u00f3stico del neurinoma del ac\u00fastico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/#%C2%BFCual_es_el_tratamiento_del_neurinoma_del_acustico\" >\u00bfCu\u00e1l es el tratamiento del neurinoma del ac\u00fastico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.ototech.es\/en\/blog\/neurinoma-acustico-2\/#%C2%BFEs_segura_la_cirugia_para_tratar_el_neurinoma_del_acustico\" >\u00bfEs segura la cirug\u00eda para tratar el neurinoma del ac\u00fastico?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_el_neurinoma_del_acustico\"><\/span><strong>\u00bfQu\u00e9 es el neurinoma del ac\u00fastico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El neurinoma del ac\u00fastico es un tumor benigno intracraneal. Recibe el nombre tambi\u00e9n de schwannoma vestibular. Su origen son las c\u00e9lulas de Schwann que recubren los nervios vestibulares.<\/p>\n\n\n\n<p>En principio no existen factores de riesgo para sufrir esta enfermedad, salvo la exposici\u00f3n elevada a la radiaci\u00f3n ionizantes que s\u00ed parece estar relacionada con la aparici\u00f3n de este tipo de tumores.<\/p>\n\n\n\n<p>Eso s\u00ed, hay una enfermedad que se llama Neurofibromatosis tipo II, que s\u00ed es hereditaria y que se relaciona con el neurinoma ac\u00fastico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_sintomas_presenta_el_neurinoma_del_acustico\"><\/span><strong>\u00bfQu\u00e9 s\u00edntomas presenta el neurinoma del ac\u00fastico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El 80 % de los pacientes que sufren neurinoma del ac\u00fastico tienen como primer s\u00edntoma la <strong><a href=\"https:\/\/www.ototech.es\/hipoacusia\/\" target=\"_blank\" rel=\"noreferrer noopener\">hipoacusia <\/a><\/strong>unilateral, mientras que el segundo que presentan son los <strong><a href=\"http:\/\/ototech.es\/acufenos-barcelona\/\" target=\"_blank\" rel=\"noreferrer noopener\">ac\u00fafenos<\/a><\/strong>. Adem\u00e1s, tambi\u00e9n pueden sufrir mareos, v\u00e9rtigos, dolor de cabeza o problemas de movilidad facial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"_%C2%BFComo_se_realiza_el_diagnostico_del_neurinoma_del_acustico\"><\/span><strong>&nbsp;\u00bfC\u00f3mo se realiza el diagn\u00f3stico del neurinoma del ac\u00fastico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para diagnosticar el neurinoma del ac\u00fastico se realiza una resonancia magn\u00e9tica con contraste, ya que facilita la observaci\u00f3n incluso de los tumores m\u00e1s peque\u00f1os.<\/p>\n\n\n\n<p>A partir de esta prueba de imagen se podr\u00e1 establecer un diagn\u00f3stico preciso, que muestre en qu\u00e9 estado se encuentra la dolencia. Como es l\u00f3gico, el siguiente paso ser\u00e1 encontrar el mejor tratamiento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_tratamiento_del_neurinoma_del_acustico\"><\/span><strong>\u00bfCu\u00e1l es el tratamiento del neurinoma del ac\u00fastico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>El tratamiento del neurinoma del ac\u00fastico depende de algunas cuestiones relacionadas con el paciente, se tiene en cuenta su edad, su estado de salud, c\u00f3mo ha afectado el tumor a la audici\u00f3n o su tama\u00f1o y localizaci\u00f3n.<\/p>\n\n\n\n<p>Estas son las tres formas en las que se controla la enfermedad:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Revisiones frecuentes y de forma peri\u00f3dica.<\/strong> El paciente es controlado de forma constante por medio de resonancias magn\u00e9ticas, una o dos veces al a\u00f1o, y es una opci\u00f3n que se puede elegir en todos estos casos:<ul><li>Pacientes ancianos.<\/li><\/ul><ul><li>Pacientes que tengan tumores de peque\u00f1o tama\u00f1o y que apenas presenten s\u00edntomas.<\/li><\/ul><ul><li>Pacientes que tengan el tumor en el \u00fanico o\u00eddo que a\u00fan escucha.<\/li><\/ul><ul><li>Pacientes con enfermedades a los que suponga un riesgo someterse a una intervenci\u00f3n quir\u00fargica.<\/li><\/ul><ul><li>Pacientes que no quieran someterse a un tratamiento invasivo.<\/li><\/ul><\/li><li><strong>Cirug\u00eda.<\/strong> Se recomienda la intervenci\u00f3n quir\u00fargica en el caso de los pacientes j\u00f3venes que tengan un tumor de un tama\u00f1o mayor a los 2,5 cent\u00edmetros. Tambi\u00e9n puede ser recomendable para los pacientes que tienen tumores peque\u00f1os y que su audici\u00f3n todav\u00eda no se ha visto afectada. La operaci\u00f3n se realiza utilizando anestesia general y se llega a la zona por medio del o\u00eddo interno o realizando una incisi\u00f3n en el cr\u00e1neo.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFEs_segura_la_cirugia_para_tratar_el_neurinoma_del_acustico\"><\/span><strong>\u00bfEs segura la cirug\u00eda para tratar el neurinoma del ac\u00fastico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Como has visto, en algunos casos ser\u00e1 preciso recurrir a la cirug\u00eda para eliminar el tumor. Es una intervenci\u00f3n segura, pero tiene algunos riesgos. Su mortalidad es inferior al 1 %, pero el riesgo de par\u00e1lisis facial, de problemas de equilibrio o de que empeore la audici\u00f3n es mayor.<\/p>\n\n\n\n<p>Por eso, otra opci\u00f3n es la radiocirug\u00eda estereot\u00e1ctica, que en realidad no es una intervenci\u00f3n quir\u00fargica. Consiste en radiar la zona en la que se encuentra el tumor para detener su crecimiento y las consecuencias que puede tener que lo haga.<\/p>\n\n\n\n<p>En cualquier caso, ser\u00e1 el otorrino el que indique al paciente cu\u00e1l es el mejor tratamiento para el neurinoma del ac\u00fastico. As\u00ed que no dejes de ponerte en<strong><a href=\"https:\/\/www.ototech.es\/contacto\/\" target=\"_blank\" rel=\"noreferrer noopener\"> contacto con nosotros<\/a><\/strong> si tienes este o cualquier otro problema relacionado con tu audici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo de la medicina es realmente apasionante. No solo porque permite curar infinidad de enfermedades, sino porque muchas de ellas son desconocidas para la mayor\u00eda. Es cierto que hay [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12],"tags":[],"class_list":["post-4542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-patologias"],"_links":{"self":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/comments?post=4542"}],"version-history":[{"count":1,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4542\/revisions"}],"predecessor-version":[{"id":4544,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4542\/revisions\/4544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media\/4543"}],"wp:attachment":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media?parent=4542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/categories?post=4542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/tags?post=4542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}