{"id":4130,"date":"2020-11-24T06:00:00","date_gmt":"2020-11-24T06:00:00","guid":{"rendered":"https:\/\/www.ototech.es\/?p=4130"},"modified":"2020-10-26T09:14:46","modified_gmt":"2020-10-26T09:14:46","slug":"sindrome-de-pendred","status":"publish","type":"post","link":"https:\/\/www.ototech.es\/en\/blog\/sindrome-de-pendred\/","title":{"rendered":"S\u00edndrome de Pendred: \u00bfEn qu\u00e9 consiste?"},"content":{"rendered":"\n<p>El <strong>s\u00edndrome de Pendred <\/strong>es una anomal\u00eda gen\u00e9tica cuyo principal rasgo es el de causar <strong><a href=\"https:\/\/www.ototech.es\/hipoacusia\/\" target=\"_blank\" rel=\"noreferrer noopener\">hipoacusia <\/a><\/strong>temprana en los ni\u00f1os. Las personas diagnosticadas con este trastorno pueden sufrir otro tipo de s\u00edntomas asociados, que detallaremos a continuaci\u00f3n. Si quieres saber m\u00e1s sobre esta enfermedad y sobre c\u00f3mo actuar ante ella, desde <strong>Ototech, expertos en acufenos en Barcelona<\/strong>, te lo contamos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 es el s\u00edndrome de Pendred<\/h2>\n\n\n\n<p>El s\u00edndrome de Pendred es una de las causas de sordera cong\u00e9nita m\u00e1s frecuentes. Se trata de una hipoacusia autos\u00f3mica recesiva, por ello, debe ser transmitida por los dos progenitores para que se exprese.<\/p>\n\n\n\n<p>La p\u00e9rdida auditiva en ni\u00f1os con s\u00edndrome de Pendred se suele presentar de forma progresiva y puede empezar desde el momento del nacimiento hasta los tres a\u00f1os.<\/p>\n\n\n\n<p>En ocasiones, este trastorno pasa desapercibido en un primer momento, sobre todo, cuando se empieza a desarrollar m\u00e1s tarde. A los reci\u00e9n nacidos se les realizan unas pruebas de cribaje para descartar problemas de audici\u00f3n al nacer, hablamos de los Potenciales Evocados auditivos. Estas pruebas consisten en registrar los cambios en los impulsos el\u00e9ctricos del cerebro cuando los o\u00eddos reciben un est\u00edmulo sonoro. Por ello, si el s\u00edndrome se empieza a desarrollar pasados los primeros meses, puede no ser diagnosticado hasta mucho m\u00e1s adelante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00edntomas del s\u00edndrome de Pendred<\/h2>\n\n\n\n<p>Junto con la p\u00e9rdida auditiva, los ni\u00f1os que nacen con este trastorno pueden presentar otros s\u00edntomas asociados. Las manifestaciones m\u00e1s comunes del s\u00edndrome de Pendred son:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>P\u00e9rdida de audici\u00f3n o sordera bilateral.<\/li><li>Hipotiroidismo.<\/li><li>Bocio.<\/li><li><strong><a href=\"https:\/\/www.ototech.es\/vertigos\/\" target=\"_blank\" rel=\"noreferrer noopener\">V\u00e9rtigos <\/a><\/strong>y problemas de equilibrio, sobre todo cuando se presentan malformaciones en los huesos del o\u00eddo interno.<\/li><\/ul>\n\n\n\n<p>No todos los ni\u00f1os que tienen este s\u00edndrome desarrollan todos los s\u00edntomas, pero s\u00ed deben ser supervisados por los facultativos correspondientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tratamiento del s\u00edndrome de Pendred<\/h2>\n\n\n\n<p>Las expectativas con respecto a este s\u00edndrome tienen mucho que ver con un diagn\u00f3stico precoz de la enfermedad.<\/p>\n\n\n\n<p>Al presentarse en los primeros a\u00f1os de vida, es importante ayudar al ni\u00f1o con su desarrollo del lenguaje. En este sentido, dependiendo del grado de hipoacusia que cause la enfermedad se podr\u00e1 actuar de diferentes maneras, bien colocando aud\u00edfonos al menor, con el apoyo de un logopeda o con diferentes terapias.<\/p>\n\n\n\n<p>Es importante, tambi\u00e9n, hacer audiometr\u00edas frecuentes para comprobar que la hipoacusia no siga avanzando. En casos muy severos se podr\u00eda llegar a pensar en un implante .<\/p>\n\n\n\n<p>As\u00ed mismo, se debe controlar la funci\u00f3n de la gl\u00e1ndula tiroidea para evitar otros trastornos asociados a su baja producci\u00f3n hormonal.<\/p>\n\n\n\n<p><strong>En Ototech somos expertos en salud auditiva<\/strong> y contamos con una terapia que ayuda a rehabilitar las c\u00e9lulas ciliares. La <strong><a href=\"https:\/\/www.ototech.es\/terapia\/\" target=\"_blank\" rel=\"noreferrer noopener\">terapia de electroestimnulaci\u00f3n <\/a><\/strong> consiste en golpear las c\u00e9lulas del interior de la  con impulsos de luz a frecuencias determinadas. Gracias a al estimulaci\u00f3n que se ejerce sobre ellas, se produce un fen\u00f3meno de rehabilitaci\u00f3n celular que ayuda a aliviar muchos de los s\u00edntomas auditivos.<\/p>\n\n\n\n<p>La <strong><a href=\"https:\/\/www.ototech.es\/terapia\/\" target=\"_blank\" rel=\"noreferrer noopener\">terapia Ototech <\/a><\/strong>puede mejorar la hipoacusia y minimizar los v\u00e9rtigos en personas con problemas auditivos. Si es tu caso, o tu hijo ha recibido un diagn\u00f3stico de s\u00edndrome de Pendred, <strong><a href=\"https:\/\/www.ototech.es\/contacto\/\" target=\"_blank\" rel=\"noreferrer noopener\">ponte en contacto con nosotros<\/a><\/strong>. Nuestra experiencia te ayudar\u00e1 a entender mejor la enfermedad y a buscar la mejor forma de tratarla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00edndrome de Pendred es una anomal\u00eda gen\u00e9tica cuyo principal rasgo es el de causar hipoacusia temprana en los ni\u00f1os. Las personas diagnosticadas con este trastorno pueden sufrir otro tipo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12],"tags":[],"class_list":["post-4130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-patologias"],"_links":{"self":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/comments?post=4130"}],"version-history":[{"count":2,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4130\/revisions"}],"predecessor-version":[{"id":4133,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/4130\/revisions\/4133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media\/4131"}],"wp:attachment":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media?parent=4130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/categories?post=4130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/tags?post=4130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}