{"id":3300,"date":"2019-09-05T06:00:37","date_gmt":"2019-09-05T06:00:37","guid":{"rendered":"https:\/\/www.ototech.es\/?p=3300"},"modified":"2019-09-09T07:09:31","modified_gmt":"2019-09-09T07:09:31","slug":"otitis","status":"publish","type":"post","link":"https:\/\/www.ototech.es\/en\/blog\/otitis\/","title":{"rendered":"\u00bfQu\u00e9 es la otitis y c\u00f3mo puede afectar a tu salud auditiva?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La<strong> otitis<\/strong> es una inflamaci\u00f3n del o\u00eddo que suele estar originada por la aparici\u00f3n y proliferaci\u00f3n de microorganismos. Es una afecci\u00f3n bastante com\u00fan y que ocasiona la mayor\u00eda de las visitas al otorrino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habitualmente, no reviste especial gravedad. Sin embargo, en ocasiones puede causar da\u00f1os auditivos. En Ototech hemos tratado innumerables pacientes con otitis y, como expertos en el <strong><a href=\"https:\/\/www.ototech.es\/acufenos\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"tratamiento de ac\u00fafenos en Barcelona (abre en una nueva pesta\u00f1a)\">tratamiento de ac\u00fafenos en Barcelona<\/a><\/strong>, hemos podido ayudar a paliar los efectos que estas han producido en sus o\u00eddos.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice del art\u00edculo<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.ototech.es\/en\/blog\/otitis\/#Que_causa_la_otitis\" >Qu\u00e9 causa la otitis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.ototech.es\/en\/blog\/otitis\/#Tipos_de_otitis\" >Tipos de otitis<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.ototech.es\/en\/blog\/otitis\/#Otitis_media_aguda\" >Otitis media aguda<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.ototech.es\/en\/blog\/otitis\/#Otitis_media_subaguda\" >Otitis media subaguda<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.ototech.es\/en\/blog\/otitis\/#Consecuencias_de_la_otitis\" >Consecuencias de la otitis<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Que_causa_la_otitis\"><\/span>Qu\u00e9 causa la otitis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>otitis <\/strong>est\u00e1 causada por una infecci\u00f3n que suele afectar al <strong>o\u00eddo medio<\/strong>. Normalmente est\u00e1 causada por la acci\u00f3n de un virus o una bacteria, siendo el agente bacteriano el m\u00e1s com\u00fan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La infecci\u00f3n suele hacer que se\nacumule fluido detr\u00e1s del t\u00edmpano. La presi\u00f3n que ejerce el l\u00edquido suele\ncausar el caracter\u00edstico dolor de esta enfermedad. As\u00ed mismo, cuando se padece\notitis tambi\u00e9n se puede sufrir tumefacci\u00f3n, y enrojecimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La inflamaci\u00f3n del o\u00eddo medio\nimpide una correcta vibraci\u00f3n del t\u00edmpano. Como consecuencia de ello, se pueden\ntener p\u00e9rdidas de audici\u00f3n pasajeras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El bloqueo de la <strong>trompa de Eustaquio<\/strong>, y por el cual no se consigue drenar el l\u00edquido del o\u00eddo, puede ser causado por:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 Elementos intr\u00ednsecos, es\ndecir, por alergias o infecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 Elementos extr\u00ednsecos,\nhabitualmente por vegetaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tipos_de_otitis\"><\/span>Tipos de otitis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El tipo m\u00e1s com\u00fan de esta\ndolencia es la otitis media. Esta, a su vez, se divide en:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Otitis_media_aguda\"><\/span>Otitis media aguda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Suele aparecer cuando se sufre un resfriado o una alergia que se complican. A veces, el moco originado por estas patolog\u00edas migra al o\u00eddo y lo infecta. El dolor es dolor es su s\u00edntoma principal, aunque no ser\u00e1 diagnosticada hasta que se pueda observar el t\u00edmpano.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Otitis_media_subaguda\"><\/span>Otitis media subaguda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n conocida como otitis media serosa, se caracteriza por la presencia de exudado (seroso, con pus, con moco o mixto). Suele cursar con s\u00edntomas mucho m\u00e1s leves que la otitis media aguda, aunque corre el riesgo de cronificarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 Otitis media cr\u00f3nica. Cuando el\nexudado dura m\u00e1s de tres meses, se considera otitis media cr\u00f3nica. Causa\nperforaci\u00f3n del t\u00edmpano y puede aparecer despu\u00e9s de un resfriad o al entrar\nagua en el canal auditivo. La supuraci\u00f3n del o\u00eddo suele ser indolora, pero\nf\u00e9tida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Consecuencias_de_la_otitis\"><\/span>Consecuencias de la otitis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Normalmente, las otitis son\ntratadas mediante la administraci\u00f3n de antibi\u00f3ticos y se curan sin\nconsecuencias importantes. Sin embargo, en ocasiones, puede cronificarse y\nproducir hipoacusia y otros problemas de audici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La otitis media puede llegar a\nocasionar la rotura del t\u00edmpano, por lo que, si los s\u00edntomas no remiten con el\ntratamiento, debe consultarse de nuevo con el otorrino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las consecuencias de la otitis\nson suficientemente importantes como para que no las dejes pasar. Si notas\npicor o dolor en el o\u00eddo, ponte en contacto con Ototech; nuestro equipo de\nespecialistas te podr\u00e1 ofrecer la mejor soluci\u00f3n para tu salud auditiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos de los pacientes que han\nllegado a nuestro centro, buscando una soluci\u00f3n para la hipoacusia, han\nreportado haber padecido otitis de forma habitual. La sordera producida por\nesta enfermedad es bastante m\u00e1s com\u00fan de lo que se podr\u00eda pensar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si sufres una p\u00e9rdida auditiva, en\u00a0<strong>Ototech<\/strong>\u00a0podemos ayudarte.\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.ototech.es\/contacto\/\" target=\"_blank\">Ponte en contacto con nosotros<\/a>\u00a0y te explicaremos c\u00f3mo nuestros especialistas en Otorrinolaringolog\u00eda y nuestra <strong><a href=\"https:\/\/www.ototech.es\/terapia\/\">terapia de   <\/a> <\/strong>pueden mejorar tus s\u00edntomas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La otitis es una inflamaci\u00f3n del o\u00eddo que suele estar originada por la aparici\u00f3n y proliferaci\u00f3n de microorganismos. Es una afecci\u00f3n bastante com\u00fan y que ocasiona la mayor\u00eda de las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[11],"tags":[],"class_list":["post-3300","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-salud-auditiva","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":3,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"predecessor-version":[{"id":3309,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/posts\/3300\/revisions\/3309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media\/3301"}],"wp:attachment":[{"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ototech.es\/en\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}